{"id":12710,"date":"2020-12-08T17:17:13","date_gmt":"2020-12-08T16:17:13","guid":{"rendered":"https:\/\/www.fcfamalicao.pt\/?p=12710"},"modified":"2020-12-08T17:17:13","modified_gmt":"2020-12-08T16:17:13","slug":"dois-ultimos-jogos-de-2020-com-data-definida","status":"publish","type":"post","link":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/","title":{"rendered":"Dois \u00faltimos jogos de 2020 com data definida"},"content":{"rendered":"<p>Est\u00e1 definido o calend\u00e1rio do Futebol Clube de Famalic\u00e3o at\u00e9 ao final do ano 2020. Al\u00e9m do jogo da 4.\u00aa eliminat\u00f3ria da Ta\u00e7a de Portugal, frente ao Rio Ave Futebol Clube e agendado para o pr\u00f3ximo s\u00e1bado (21 horas), a equipa orientada por Jo\u00e3o Pedro Sousa j\u00e1 conhece as datas em que ir\u00e1 entrar em campo no m\u00eas de dezembro.<\/p>\n<p>A desloca\u00e7\u00e3o a Portim\u00e3o para defrontar o Portimonense Sporting Clube far\u00e1 a abertura da 10.\u00aa jornada da Liga NOS e est\u00e1 marcada para 20h30 do dia 18 de dezembro (sexta-feira). J\u00e1 o \u00faltimo jogo do presente ano civil ter\u00e1 lugar no Est\u00e1dio Municipal de Famalic\u00e3o, no dia 27 de dezembro (domingo), pelas 15 horas, em partida em que o Futebol Clube de Famalic\u00e3o vai defrontar o Gil Vicente Futebol Clube.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 definido o calend\u00e1rio do Futebol Clube de Famalic\u00e3o at\u00e9 ao final do ano 2020. Al\u00e9m do jogo da 4.\u00aa eliminat\u00f3ria da Ta\u00e7a de Portugal, frente ao Rio Ave Futebol Clube e agendado para o pr\u00f3ximo s\u00e1bado (21 horas), a equipa orientada por Jo\u00e3o Pedro Sousa j\u00e1 conhece as datas&hellip;<\/p>\n","protected":false},"author":2,"featured_media":12711,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dois \u00faltimos jogos de 2020 com data definida - FC Famalic\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dois \u00faltimos jogos de 2020 com data definida - FC Famalic\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 definido o calend\u00e1rio do Futebol Clube de Famalic\u00e3o at\u00e9 ao final do ano 2020. Al\u00e9m do jogo da 4.\u00aa eliminat\u00f3ria da Ta\u00e7a de Portugal, frente ao Rio Ave Futebol Clube e agendado para o pr\u00f3ximo s\u00e1bado (21 horas), a equipa orientada por Jo\u00e3o Pedro Sousa j\u00e1 conhece as datas&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/\" \/>\n<meta property=\"og:site_name\" content=\"FC Famalic\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FCFamalicao\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T16:17:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fcfamalicao fcfamalicao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fcf1931_oficial\" \/>\n<meta name=\"twitter:site\" content=\"@fcf1931_oficial\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fcfamalicao fcfamalicao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/\"},\"author\":{\"name\":\"fcfamalicao fcfamalicao\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/713a4d367f5259360c363ad35dad9247\"},\"headline\":\"Dois \u00faltimos jogos de 2020 com data definida\",\"datePublished\":\"2020-12-08T16:17:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/\"},\"wordCount\":144,\"publisher\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/\",\"url\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/\",\"name\":\"Dois \u00faltimos jogos de 2020 com data definida - FC Famalic\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg\",\"datePublished\":\"2020-12-08T16:17:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#primaryimage\",\"url\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg\",\"contentUrl\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fcfamalicao.pt\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dois \u00faltimos jogos de 2020 com data definida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#website\",\"url\":\"https:\/\/www.fcfamalicao.pt\/en\/\",\"name\":\"FC Famalic\u00e3o\",\"description\":\"Site oficial do Futebol Clube Famalic\u00e3o. #AMORDEPERDI\u00c7\u00c3O\",\"publisher\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fcfamalicao.pt\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#organization\",\"name\":\"FC Famalic\u00e3o\",\"url\":\"https:\/\/www.fcfamalicao.pt\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2018\/11\/fcf-logo.png\",\"contentUrl\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2018\/11\/fcf-logo.png\",\"width\":150,\"height\":143,\"caption\":\"FC Famalic\u00e3o\"},\"image\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FCFamalicao\/\",\"https:\/\/x.com\/fcf1931_oficial\",\"https:\/\/www.instagram.com\/futebolclubefamalicao\/\",\"https:\/\/www.youtube.com\/FCFamalicao1931\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/713a4d367f5259360c363ad35dad9247\",\"name\":\"fcfamalicao fcfamalicao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b37399ebd6c6b1f9808b97ddeec50eb3b762cc626cb1e17e3a8b30044160d118?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b37399ebd6c6b1f9808b97ddeec50eb3b762cc626cb1e17e3a8b30044160d118?s=96&d=mm&r=g\",\"caption\":\"fcfamalicao fcfamalicao\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dois \u00faltimos jogos de 2020 com data definida - FC Famalic\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/","og_locale":"en_US","og_type":"article","og_title":"Dois \u00faltimos jogos de 2020 com data definida - FC Famalic\u00e3o","og_description":"Est\u00e1 definido o calend\u00e1rio do Futebol Clube de Famalic\u00e3o at\u00e9 ao final do ano 2020. Al\u00e9m do jogo da 4.\u00aa eliminat\u00f3ria da Ta\u00e7a de Portugal, frente ao Rio Ave Futebol Clube e agendado para o pr\u00f3ximo s\u00e1bado (21 horas), a equipa orientada por Jo\u00e3o Pedro Sousa j\u00e1 conhece as datas&hellip;","og_url":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/","og_site_name":"FC Famalic\u00e3o","article_publisher":"https:\/\/www.facebook.com\/FCFamalicao\/","article_published_time":"2020-12-08T16:17:13+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg","type":"image\/jpeg"}],"author":"fcfamalicao fcfamalicao","twitter_card":"summary_large_image","twitter_creator":"@fcf1931_oficial","twitter_site":"@fcf1931_oficial","twitter_misc":{"Written by":"fcfamalicao fcfamalicao","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#article","isPartOf":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/"},"author":{"name":"fcfamalicao fcfamalicao","@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/713a4d367f5259360c363ad35dad9247"},"headline":"Dois \u00faltimos jogos de 2020 com data definida","datePublished":"2020-12-08T16:17:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/"},"wordCount":144,"publisher":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/#organization"},"image":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/","url":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/","name":"Dois \u00faltimos jogos de 2020 com data definida - FC Famalic\u00e3o","isPartOf":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#primaryimage"},"image":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg","datePublished":"2020-12-08T16:17:13+00:00","breadcrumb":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#primaryimage","url":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg","contentUrl":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2020\/12\/Jogos.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.fcfamalicao.pt\/en\/dois-ultimos-jogos-de-2020-com-data-definida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fcfamalicao.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Dois \u00faltimos jogos de 2020 com data definida"}]},{"@type":"WebSite","@id":"https:\/\/www.fcfamalicao.pt\/en\/#website","url":"https:\/\/www.fcfamalicao.pt\/en\/","name":"FC Famalic\u00e3o","description":"Site oficial do Futebol Clube Famalic\u00e3o. #AMORDEPERDI\u00c7\u00c3O","publisher":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fcfamalicao.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fcfamalicao.pt\/en\/#organization","name":"FC Famalic\u00e3o","url":"https:\/\/www.fcfamalicao.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2018\/11\/fcf-logo.png","contentUrl":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2018\/11\/fcf-logo.png","width":150,"height":143,"caption":"FC Famalic\u00e3o"},"image":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FCFamalicao\/","https:\/\/x.com\/fcf1931_oficial","https:\/\/www.instagram.com\/futebolclubefamalicao\/","https:\/\/www.youtube.com\/FCFamalicao1931"]},{"@type":"Person","@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/713a4d367f5259360c363ad35dad9247","name":"fcfamalicao fcfamalicao","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b37399ebd6c6b1f9808b97ddeec50eb3b762cc626cb1e17e3a8b30044160d118?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b37399ebd6c6b1f9808b97ddeec50eb3b762cc626cb1e17e3a8b30044160d118?s=96&d=mm&r=g","caption":"fcfamalicao fcfamalicao"}}]}},"_links":{"self":[{"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/posts\/12710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/comments?post=12710"}],"version-history":[{"count":0,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/posts\/12710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/media\/12711"}],"wp:attachment":[{"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/media?parent=12710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/categories?post=12710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/tags?post=12710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}