{"id":16194,"date":"2021-08-09T12:41:12","date_gmt":"2021-08-09T12:41:12","guid":{"rendered":"https:\/\/www.fcfamalicao.pt\/?p=16194"},"modified":"2021-08-09T12:51:40","modified_gmt":"2021-08-09T12:51:40","slug":"bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais","status":"publish","type":"post","link":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/","title":{"rendered":"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais"},"content":{"rendered":"<p>O Futebol Clube de Famalic\u00e3o informa que os bilhetes para o jogo frente ao Futebol Clube do Porto, relativo \u00e0 2.\u00aa jornada da Liga Portugal Bwin, ser\u00e3o colocados \u00e0 venda a partir de quarta-feira mediante os seguintes crit\u00e9rios:<\/p>\n<ul>\n<li><strong>Quarta e Quinta-feira<br \/>\n<\/strong>Bilhete dispon\u00edvel apenas para s\u00f3cios detentores de lugar anual (\u00e9poca 2019\/2020). Ser\u00e1 necess\u00e1rio o levantamento do bilhete na Loja Oficial<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Sexta-feira<br \/>\n<\/strong>Exclusivo a S\u00f3cios com lugar anual e s\u00f3cios do FC Famalic\u00e3o at\u00e9 ao n\u00ba 3000 com quota 7 regularizada. Venda dependente da disponibilidade de ingressos<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>S\u00e1bado<br \/>\n<\/strong>Exclusivo a S\u00f3cios com lugar anual e s\u00f3cios do FC Famalic\u00e3o (a partir do n\u00ba 3000) com quota 7 regularizada. Venda dependente da disponibilidade de ingressos e apenas para s\u00f3cios inscritos at\u00e9 15 de julho.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>BILHETE DE S\u00d3CIO:<\/strong> 8 euros<\/p>\n<ul>\n<li><span style=\"font-size: inherit;\">Para al\u00e9m das habituais condi\u00e7\u00f5es de acesso e perman\u00eancia em espet\u00e1culos desportivos desta natureza, informa-se que os titulares de bilhetes v\u00e1lidos para este jogo ter\u00e3o de cumprir os requisitos e recomenda\u00e7\u00f5es emanados pela Dire\u00e7\u00e3o-Geral de Sa\u00fade para entrada no recinto desportivo, nomeadamente:<\/span><\/li>\n<\/ul>\n<p>\u2013 Certificado Digital Covid-19 v\u00e1lido, que comprove vacina\u00e7\u00e3o completa, <strong>ou<\/strong><\/p>\n<p>\u2013 Teste PCR com resultado negativo realizado at\u00e9 72 horas antes do jogo, <strong style=\"font-size: inherit;\">ou<\/strong><\/p>\n<p>\u2013 Teste antig\u00e9nio com resultado negativo realizado at\u00e9 48 horas antes do jogo, <strong>ou<\/strong><\/p>\n<ul>\n<li>\u2013 Certificado de Recupera\u00e7\u00e3o;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><\/li>\n<li>\u2013 Temperatura corporal inferior a 38 \u00ba C, mediante controlo de temperatura no acesso ao recinto.<\/li>\n<li><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m destas condi\u00e7\u00f5es \u00e9 obrigat\u00f3rio o uso permanente da m\u00e1scara de prote\u00e7\u00e3o e a manuten\u00e7\u00e3o do distanciamento f\u00edsico.<\/p>\n<p><strong><br \/>\nINFORMA\u00c7\u00d5ES SOBRE LUGARES ANUAIS<\/strong><\/p>\n<p>Tendo em conta as circunst\u00e2ncias que impediram que os s\u00f3cios detentores de lugar anual usufru\u00edssem do servi\u00e7o durante a totalidade da temporada 2019-2020, o Futebol Clube de Famalic\u00e3o anuncia as condi\u00e7\u00f5es para a presente \u00e9poca desportiva:<\/p>\n<ul>\n<li class=\"p1\"><span class=\"s1\"><strong>S\u00f3cio<\/strong><b> detentor de Lugar Anual 2019\/20<\/b><\/span><\/li>\n<li class=\"p1\">&#8211; Entrada gratuita nos primeiros cinco jogos da Liga Portugal Bwin no Est\u00e1dio Municipal de Famalic\u00e3o, nomeadamente nos jogos frente a FC Porto, Sporting CP, CS Mar\u00edtimo, Vit\u00f3ria SC e FC Vizela. Em todos os referidos jogos, o s\u00f3cio ter\u00e1, necessariamente, de ser portador de um bilhete para aceder ao jogo;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&#8211; A partir do jogo frente ao Portimonense SC (inclusive), relativo \u00e0 12.\u00aa jornada da Liga Portugal Bwin e o sexto a realizar no Est\u00e1dio Municipal de Famalic\u00e3o esta temporada, ser\u00e1 cobrado um bilhete de s\u00f3cio para acesso ao jogo. O detentor de lugar anual ter\u00e1 sempre prioridade na aquisi\u00e7\u00e3o de ingresso para os jogos do Futebol Clube de Famalic\u00e3o a realizar no Est\u00e1dio Municipal;<\/p>\n<ul>\n<li><\/li>\n<li>&#8211; Enquanto se mantiverem as atuais restri\u00e7\u00f5es de capacidade, em virtude das normas da Dire\u00e7\u00e3o-Geral de Sa\u00fade, o Futebol Clube de Famalic\u00e3o n\u00e3o proceder\u00e1 \u00e0 renova\u00e7\u00e3o ou venda de lugares anuais.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>O Futebol Clube de Famalic\u00e3o informa que os bilhetes para o jogo frente ao Futebol Clube do Porto, relativo \u00e0 2.\u00aa jornada da Liga Portugal Bwin, ser\u00e3o colocados \u00e0 venda a partir de quarta-feira mediante os seguintes crit\u00e9rios: Quarta e Quinta-feira Bilhete dispon\u00edvel apenas para s\u00f3cios detentores de lugar anual&hellip;<\/p>\n","protected":false},"author":2,"featured_media":16195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais - FC Famalic\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais - FC Famalic\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O Futebol Clube de Famalic\u00e3o informa que os bilhetes para o jogo frente ao Futebol Clube do Porto, relativo \u00e0 2.\u00aa jornada da Liga Portugal Bwin, ser\u00e3o colocados \u00e0 venda a partir de quarta-feira mediante os seguintes crit\u00e9rios: Quarta e Quinta-feira Bilhete dispon\u00edvel apenas para s\u00f3cios detentores de lugar anual&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/\" \/>\n<meta property=\"og:site_name\" content=\"FC Famalic\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FCFamalicao\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-09T12:41:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-09T12:51:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fcfamalicao fcfamalicao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fcf1931_oficial\" \/>\n<meta name=\"twitter:site\" content=\"@fcf1931_oficial\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fcfamalicao fcfamalicao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/\"},\"author\":{\"name\":\"fcfamalicao fcfamalicao\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/713a4d367f5259360c363ad35dad9247\"},\"headline\":\"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais\",\"datePublished\":\"2021-08-09T12:41:12+00:00\",\"dateModified\":\"2021-08-09T12:51:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/\"},\"wordCount\":494,\"publisher\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/\",\"url\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/\",\"name\":\"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais - FC Famalic\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg\",\"datePublished\":\"2021-08-09T12:41:12+00:00\",\"dateModified\":\"2021-08-09T12:51:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#primaryimage\",\"url\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg\",\"contentUrl\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fcfamalicao.pt\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#website\",\"url\":\"https:\/\/www.fcfamalicao.pt\/en\/\",\"name\":\"FC Famalic\u00e3o\",\"description\":\"Site oficial do Futebol Clube Famalic\u00e3o. #AMORDEPERDI\u00c7\u00c3O\",\"publisher\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fcfamalicao.pt\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#organization\",\"name\":\"FC Famalic\u00e3o\",\"url\":\"https:\/\/www.fcfamalicao.pt\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2018\/11\/fcf-logo.png\",\"contentUrl\":\"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2018\/11\/fcf-logo.png\",\"width\":150,\"height\":143,\"caption\":\"FC Famalic\u00e3o\"},\"image\":{\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FCFamalicao\/\",\"https:\/\/x.com\/fcf1931_oficial\",\"https:\/\/www.instagram.com\/futebolclubefamalicao\/\",\"https:\/\/www.youtube.com\/FCFamalicao1931\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/713a4d367f5259360c363ad35dad9247\",\"name\":\"fcfamalicao fcfamalicao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b37399ebd6c6b1f9808b97ddeec50eb3b762cc626cb1e17e3a8b30044160d118?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b37399ebd6c6b1f9808b97ddeec50eb3b762cc626cb1e17e3a8b30044160d118?s=96&d=mm&r=g\",\"caption\":\"fcfamalicao fcfamalicao\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais - FC Famalic\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/","og_locale":"en_US","og_type":"article","og_title":"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais - FC Famalic\u00e3o","og_description":"O Futebol Clube de Famalic\u00e3o informa que os bilhetes para o jogo frente ao Futebol Clube do Porto, relativo \u00e0 2.\u00aa jornada da Liga Portugal Bwin, ser\u00e3o colocados \u00e0 venda a partir de quarta-feira mediante os seguintes crit\u00e9rios: Quarta e Quinta-feira Bilhete dispon\u00edvel apenas para s\u00f3cios detentores de lugar anual&hellip;","og_url":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/","og_site_name":"FC Famalic\u00e3o","article_publisher":"https:\/\/www.facebook.com\/FCFamalicao\/","article_published_time":"2021-08-09T12:41:12+00:00","article_modified_time":"2021-08-09T12:51:40+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg","type":"image\/jpeg"}],"author":"fcfamalicao fcfamalicao","twitter_card":"summary_large_image","twitter_creator":"@fcf1931_oficial","twitter_site":"@fcf1931_oficial","twitter_misc":{"Written by":"fcfamalicao fcfamalicao","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#article","isPartOf":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/"},"author":{"name":"fcfamalicao fcfamalicao","@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/713a4d367f5259360c363ad35dad9247"},"headline":"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais","datePublished":"2021-08-09T12:41:12+00:00","dateModified":"2021-08-09T12:51:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/"},"wordCount":494,"publisher":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/#organization"},"image":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/","url":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/","name":"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais - FC Famalic\u00e3o","isPartOf":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#primaryimage"},"image":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg","datePublished":"2021-08-09T12:41:12+00:00","dateModified":"2021-08-09T12:51:40+00:00","breadcrumb":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#primaryimage","url":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg","contentUrl":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2021\/08\/P\u00fablico_Easy-Resize.com_.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.fcfamalicao.pt\/en\/bilhetes-para-o-jogo-fc-famalicao-x-fc-porto-e-lugares-anuais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fcfamalicao.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Bilhetes para o jogo FC Famalic\u00e3o x FC Porto e Lugares Anuais"}]},{"@type":"WebSite","@id":"https:\/\/www.fcfamalicao.pt\/en\/#website","url":"https:\/\/www.fcfamalicao.pt\/en\/","name":"FC Famalic\u00e3o","description":"Site oficial do Futebol Clube Famalic\u00e3o. #AMORDEPERDI\u00c7\u00c3O","publisher":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fcfamalicao.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fcfamalicao.pt\/en\/#organization","name":"FC Famalic\u00e3o","url":"https:\/\/www.fcfamalicao.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2018\/11\/fcf-logo.png","contentUrl":"https:\/\/www.fcfamalicao.pt\/wp-content\/uploads\/2018\/11\/fcf-logo.png","width":150,"height":143,"caption":"FC Famalic\u00e3o"},"image":{"@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FCFamalicao\/","https:\/\/x.com\/fcf1931_oficial","https:\/\/www.instagram.com\/futebolclubefamalicao\/","https:\/\/www.youtube.com\/FCFamalicao1931"]},{"@type":"Person","@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/713a4d367f5259360c363ad35dad9247","name":"fcfamalicao fcfamalicao","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fcfamalicao.pt\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b37399ebd6c6b1f9808b97ddeec50eb3b762cc626cb1e17e3a8b30044160d118?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b37399ebd6c6b1f9808b97ddeec50eb3b762cc626cb1e17e3a8b30044160d118?s=96&d=mm&r=g","caption":"fcfamalicao fcfamalicao"}}]}},"_links":{"self":[{"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/posts\/16194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/comments?post=16194"}],"version-history":[{"count":0,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/posts\/16194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/media\/16195"}],"wp:attachment":[{"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/media?parent=16194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/categories?post=16194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcfamalicao.pt\/en\/wp-json\/wp\/v2\/tags?post=16194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}